{"id":1721,"date":"2020-09-30T17:23:02","date_gmt":"2020-09-30T15:23:02","guid":{"rendered":"https:\/\/www.unioviedo.es\/catedraIPA\/?p=1721"},"modified":"2020-09-30T17:39:33","modified_gmt":"2020-09-30T15:39:33","slug":"dos-cientificas-en-el-mundo-de-la-viticultura-heroica-de-cangas","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/catedraIPA\/dos-cientificas-en-el-mundo-de-la-viticultura-heroica-de-cangas\/","title":{"rendered":"Dos cient\u00edficas en el mundo de la viticultura heroica de Cangas"},"content":{"rendered":"<p>El pasado d\u00eda, 17 de septiembre, tuvo lugar el segundo &#8216;Falucando&#8217;, en esta ocasi\u00f3n para conocer m\u00e1s en profundidad el Vino de Cangas, una de las se\u00f1as de identidad del Principado en cuanto a gastronom\u00eda se refiere. Ismael Marcet, de la C\u00e1tedra IPA, dirigi\u00f3 el coloquio online planteando una serie de temas relevantes en cuanto a la elaboraci\u00f3n del vino de Cangas, y sus aspectos diferenciales con respecto a otros vinos nacionales.<\/p>\n<p>Se pudo contar con el testimonio de dos mujeres que conocen muy de cerca la viticultura de la zona de Cangas, una de ellas siendo directora de la Bodega Vidas, Beatriz P\u00e9rez, y en el segundo caso, siendo investigadora del CSIC en el \u00e1rea de viticultura, Carmen Mart\u00ednez, cuya familia dirige la Bodega Vitheras. Ambas, desde diferentes puntos de vista debido a sus trayectorias profesionales, compartieron con nosotros datos muy interesantes con respecto al Vino de Cangas.<\/p>\n<p>Aunque no compartieron opini\u00f3n en cu\u00e1nto a la calidad del vino tinto de la zona con respecto al blanco, las dos coinciden en que se trata de una zona con grandes dificultades debido a su orograf\u00eda, y al tama\u00f1o y disposici\u00f3n de las parcelas cultivables. Tambi\u00e9n reclaman a las administraciones p\u00fablicas una serie de peticiones para poder proteger este producto de calidad diferenciada, que es una de los pocos recursos de la zona de Cangas.<\/p>\n<p>\u00a0<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"576\" src=\"https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-1024x576.jpg\" alt=\"\" class=\"wp-image-1724\" srcset=\"https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-1024x576.jpg 1024w, https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-300x169.jpg 300w, https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-768x432.jpg 768w, https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-570x321.jpg 570w, https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-1110x624.jpg 1110w, https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas-528x297.jpg 528w, https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2020\/09\/Cartel-coloquio-vino-de-Cangas.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El pasado d\u00eda, 17 de septiembre, tuvo lugar el segundo &#8216;Falucando&#8217;, en esta ocasi\u00f3n para conocer m\u00e1s en profundidad el Vino de Cangas, una de las se\u00f1as de identidad del Principado en cuanto a gastronom\u00eda se refiere. Ismael Marcet, de la C\u00e1tedra IPA, dirigi\u00f3 el coloquio online planteando una serie de temas relevantes en cuanto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/posts\/1721"}],"collection":[{"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":3,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":1728,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/posts\/1721\/revisions\/1728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/media\/1727"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedraIPA\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}