{"id":258,"date":"2022-08-03T13:50:02","date_gmt":"2022-08-03T11:50:02","guid":{"rendered":"https:\/\/www.unioviedo.es\/catedrasidra\/?p=258"},"modified":"2022-08-03T13:50:02","modified_gmt":"2022-08-03T11:50:02","slug":"la-cultura-sidrera-esencia-dasturies-conexion-natural","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/2022\/08\/03\/la-cultura-sidrera-esencia-dasturies-conexion-natural\/","title":{"rendered":"La Cultura Sidrera, esencia d\u00b4Asturies. Conexi\u00f3n natural"},"content":{"rendered":"\n<p><strong>Luis Benito Garc\u00eda \u00c1lvarez, director de la C\u00e1tedra de la Sidra de Asturias, comisario de la exposici\u00f3n del pabell\u00f3n del Principado de Asturias de la FIDMA<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"668\" src=\"https:\/\/www.unioviedo.es\/catedrasidra\/wp-content\/uploads\/2022\/08\/R9meWmQYUz3CN9u58xcECamftaUudu2W-1024x668.jpg\" alt=\"\" class=\"wp-image-260\" srcset=\"https:\/\/www.unioviedo.es\/catedrasidra\/wp-content\/uploads\/2022\/08\/R9meWmQYUz3CN9u58xcECamftaUudu2W-1024x668.jpg 1024w, https:\/\/www.unioviedo.es\/catedrasidra\/wp-content\/uploads\/2022\/08\/R9meWmQYUz3CN9u58xcECamftaUudu2W-300x196.jpg 300w, https:\/\/www.unioviedo.es\/catedrasidra\/wp-content\/uploads\/2022\/08\/R9meWmQYUz3CN9u58xcECamftaUudu2W-768x501.jpg 768w, https:\/\/www.unioviedo.es\/catedrasidra\/wp-content\/uploads\/2022\/08\/R9meWmQYUz3CN9u58xcECamftaUudu2W.jpg 1150w\" sizes=\"auto, (max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/figure>\n\n\n\n<p>El Gobierno del Principado presenta en el pabell\u00f3n de la Feria Internacional de Muestras de Asturias (FIDMA) la muestra expositiva&nbsp;<em>La Cultura Sidrera, esencia d\u00b4 Asturies. Conexi\u00f3n natural<\/em>&nbsp;con la que a\u00fana tradici\u00f3n, innovaci\u00f3n y sostenibilidad y que mostrar\u00e1 al visitante la importante transformaci\u00f3n llevada a cabo en la regi\u00f3n a partir de dos importantes elementos vertebradores del territorio como son la sidra y el ferrocarril.<\/p>\n\n\n\n<p>El visitante de&nbsp;<em>La Cultura Sidrera, esencia d\u00b4Asturies&nbsp;<\/em>descubrir\u00e1 como, hoy, la cultura sidrera ha sabido adaptarse modernizando procesos, innovando y buscando la excelencia del producto y todo sin perder ninguna de sus se\u00f1as de identidad esenciales que hacen de esta cultura milenaria uno de los principales emblemas de Asturias.&nbsp;A trav\u00e9s de paneles y audiovisuales, el p\u00fablico que visite el pabell\u00f3n podr\u00e1 conocer los diferentes tipos de manzanas utilizados para elaborar la sidra; descubrir un llagar tradicional o uno m\u00e1s moderno y todas las empresas auxiliares que pivotan en torno al ciclo de la sidra. Adem\u00e1s, descubrir\u00e1 las caracter\u00edsticas de la sidra espumosa y de la natural con DOP, antes de probar su habilidad en el t\u00fanel de escanciado y&nbsp; sacarse una foto en un aut\u00e9ntico chigre tradicional asturiano.<\/p>\n\n\n\n<p>El Pabell\u00f3n del Principado en FIDMA dedica, adem\u00e1s, su planta baja a la llegada del AVE a Asturias, un importante hito en las comunicaciones de la regi\u00f3n. En la exposici\u00f3n C<em>onexi\u00f3n natural. La Alta Velocidad llega a Asturias<\/em>, el Administrador de Infraestructuras Ferroviarias (ADIF) muestra, a trav\u00e9s de infograf\u00edas e im\u00e1genes, los grandes hitos en ingenier\u00eda, sostenibilidad y conexi\u00f3n que ha realizado en la l\u00ednea de alta velocidad que conectar\u00e1 Oviedo\/Uvi\u00e9u con Madrid de una forma envolvente e innovadora.\u00a0Los visitantes podr\u00e1n comparar y comprender los beneficios que traer\u00e1 la nueva l\u00ednea de alta velocidad, llevarse una foto gracias a un espejo interactivo y disfrutar de un audiovisual inmersivo, en el que los paisajes asturianos cobran especial protagonismo y que descubre el reto que ha supuesto para la ingenier\u00eda espa\u00f1ola sortear la muralla natural de la Cordillera Cant\u00e1brica en un proyecto que crear\u00e1 una conexi\u00f3n natural de Asturias con el mundo.<\/p>\n\n\n\n<p><strong>Actividades complementarias en el pabell\u00f3n del Principado en FIDMA<\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<ul class=\"wp-block-list\"><li>S\u00e1bado 6 de agosto. De 12:30 a 13:30 y de 18:30 a 19:30 horas. Taller familiar El origen de la sidra\u2026 las manzanas.<\/li><li>Domingo 7 de agosto a las 19:00 horas. Festival musical de canciones tradicionales y populares en torno a la sidra y la manzana con Anabel Santiago.<\/li><li>Jueves 11 de agosto. De 11:30 a 14:30 y de 18:30 a 20:30 horas.\u00a0InmerSidra: pon a prueba en un entorno de realidad virtual tu destreza<br>escanciando Sidra de Asturias.<\/li><li>S\u00e1bado 13, domingo 14 y lunes 15 de agosto. De 12:00 a 14:00 y de 18:00 a 20:00 horas. Actividades de animaci\u00f3n Juega a lo grande y pon a prueba tu punter\u00eda y precisi\u00f3n con el juego de la Rana Gigante.<\/li><li>Jueves 18 de agosto a las 18:30 horas.\u00a0\u00a1Ven a echar un culete!\u00a0Masterclass participativa con la escanciadora sierense Loreto Garc\u00eda.<\/li><li>S\u00e1bado 20 de agosto a las 12:30 y 18:30 horas. Cuentos, pomaradas y llagares, narraci\u00f3n oral con David Acera.<\/li><\/ul>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<p><strong>Gij\u00f3n<\/strong><\/p>\n\n\n\n<p><strong>Del 6 al 21 de agosto de 2022<\/strong><\/p>\n\n\n\n<p><strong>Horario de visita<\/strong>: de 11:00 a 14:30 y de 16:30 a 21:00 horas<\/p>\n\n\n\n<p><strong>Recinto Ferial Luis Adaro<\/strong><\/p>\n\n\n\n<p>33203 Gij\u00f3n\/Xix\u00f3n<\/p>\n\n\n\n<p>T: 985 180 100<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Benito Garc\u00eda \u00c1lvarez, director de la C\u00e1tedra de la Sidra de Asturias, comisario de la exposici\u00f3n del pabell\u00f3n del Principado de Asturias de la FIDMA El Gobierno del Principado presenta en el pabell\u00f3n de la Feria Internacional de Muestras de Asturias (FIDMA) la muestra expositiva&nbsp;La Cultura Sidrera, esencia d\u00b4 Asturies. Conexi\u00f3n natural&nbsp;con la que &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/2022\/08\/03\/la-cultura-sidrera-esencia-dasturies-conexion-natural\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa Cultura Sidrera, esencia d\u00b4Asturies. Conexi\u00f3n natural\u00bb<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[24,9,33,34],"class_list":["post-258","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-asturias","tag-culturasidrera","tag-fidma","tag-sidranatural"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/posts\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":1,"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/posts\/258\/revisions"}],"predecessor-version":[{"id":261,"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/posts\/258\/revisions\/261"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/media?parent=258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/categories?post=258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/catedrasidra\/index.php\/wp-json\/wp\/v2\/tags?post=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}