{"id":40770,"date":"2021-08-01T14:52:08","date_gmt":"2021-08-01T14:52:08","guid":{"rendered":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/publicaciones\/instruccion-para-la-formacion-de-un-diccionario-del-dialecto-asturiano\/"},"modified":"2021-08-01T14:52:08","modified_gmt":"2021-08-01T14:52:08","slug":"instruccion-para-la-formacion-de-un-diccionario-del-dialecto-asturiano","status":"publish","type":"publicaciones","link":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/publicaciones\/instruccion-para-la-formacion-de-un-diccionario-del-dialecto-asturiano\/","title":{"rendered":"Instrucci\u00f3n para la formaci\u00f3n de un diccionario del dialecto asturiano"},"content":{"rendered":"","protected":false},"template":"","tomos":[328],"adjuntos":[],"class_list":["post-40770","publicaciones","type-publicaciones","status-publish","hentry","tomos-escritos-asturianos","description-off"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/publicaciones\/40770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/publicaciones"}],"about":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/types\/publicaciones"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/media?parent=40770"}],"wp:term":[{"taxonomy":"tomos","embeddable":true,"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/tomos?post=40770"},{"taxonomy":"adjuntos","embeddable":true,"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/adjuntos?post=40770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}