{"id":41143,"date":"2021-08-01T14:56:16","date_gmt":"2021-08-01T14:56:16","guid":{"rendered":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/publicaciones\/oracion-sobre-la-necesidad-de-unir-el-estudio-de-la-literatura-al-de-las-ciencias\/"},"modified":"2021-08-01T14:56:16","modified_gmt":"2021-08-01T14:56:16","slug":"oracion-sobre-la-necesidad-de-unir-el-estudio-de-la-literatura-al-de-las-ciencias","status":"publish","type":"publicaciones","link":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/publicaciones\/oracion-sobre-la-necesidad-de-unir-el-estudio-de-la-literatura-al-de-las-ciencias\/","title":{"rendered":"Oraci\u00f3n sobre la necesidad de unir el estudio de la literatura al de las ciencias."},"content":{"rendered":"","protected":false},"template":"","tomos":[332],"adjuntos":[],"class_list":["post-41143","publicaciones","type-publicaciones","status-publish","hentry","tomos-escritos-pedagogicos-1o","description-off"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/publicaciones\/41143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/publicaciones"}],"about":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/types\/publicaciones"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/media?parent=41143"}],"wp:term":[{"taxonomy":"tomos","embeddable":true,"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/tomos?post=41143"},{"taxonomy":"adjuntos","embeddable":true,"href":"https:\/\/www.unioviedo.es\/jovellanos\/index.php\/wp-json\/wp\/v2\/adjuntos?post=41143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}