{"id":443,"date":"2019-11-29T10:21:31","date_gmt":"2019-11-29T10:21:31","guid":{"rendered":"https:\/\/www.unioviedo.es\/poloalimentario\/?p=443"},"modified":"2019-11-29T10:21:33","modified_gmt":"2019-11-29T10:21:33","slug":"jornada-con-empresas-del-polo-alimentario","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/poloalimentario\/jornada-con-empresas-del-polo-alimentario\/","title":{"rendered":"Jornada con empresas del Polo Alimentario"},"content":{"rendered":"\n<p> El pasado d\u00eda 27 de noviembre tuvo lugar una enriquecedora reuni\u00f3n en la que fluy\u00f3 la comunicaci\u00f3n entre representantes de diferentes empresas del Polo Alimentario de la Universidad de Oviedo y representantes del grupo de investigaci\u00f3n de Tecnolog\u00eda de Bioprocesos y Reactores (TBR), del Departamento de Ingenier\u00eda Qu\u00edmica y Tecnolog\u00eda del Medio Ambiente de la Facultad de Qu\u00edmica. El Polo Alimentario esta constituido por un grupo de empresas que han manifestado su inter\u00e9s en el fomento de la actividad formativa, investigadora, de transferencia y difusi\u00f3n en el campo alimentario, para cuyo fin han considerado necesaria la colaboraci\u00f3n entre los sectores empresarial, institucional y universitario. Entre otras actividades manifiestan el reconocimiento de la formaci\u00f3n en Biotecnolog\u00eda alimentaria y la participaci\u00f3n por la empresa en definir las necesidades docentes en este campo. Tambi\u00e9n manifiestan el inter\u00e9s en la colaboraci\u00f3n en los campos de investigaci\u00f3n. La firma del acuerdo entre las empresas que se incorporan al comit\u00e9 de patronazgo del M\u00e1ster en Biotecnolog\u00eda Alimentaria, y el Rector de la Universidad de Oviedo se realiz\u00f3 el 16 de febrero de 2005. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2019\/11\/foto-para-noticia-1024x703.jpg\" alt=\"\" class=\"wp-image-444\" srcset=\"https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2019\/11\/foto-para-noticia-1024x703.jpg 1024w, https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2019\/11\/foto-para-noticia-250x172.jpg 250w, https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2019\/11\/foto-para-noticia-768x527.jpg 768w, https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2019\/11\/foto-para-noticia-570x391.jpg 570w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption><br><\/figcaption><\/figure>\n\n\n\n<p>En dicha jornada se present\u00f3 adem\u00e1s, ante los representantes del Polo Alimentario, la actividad que se est\u00e1 llevando a cabo en la C\u00e1tedra Caja Rural de Industrias y Procesos Agroalimentarios (C\u00e1tedra IPA), de reciente creaci\u00f3n. <\/p>\n\n\n\n<p>Dentro de la programaci\u00f3n, se cont\u00f3 con la intervenci\u00f3n de Margarita Bances, del Laboratorio de Salud P\u00fablica del Principado de Asturias, en la que expuso detalladamente varios aspectos relacionados con la problem\u00e1tica de la <em>Listeria<\/em> en la industria alimentaria, como las \u00faltimas legislaciones al respecto, o las correctas pr\u00e1cticas a la hora de realizar controles de presencia en instalaciones.<\/p>\n\n\n\n<p>Tambi\u00e9n se cont\u00f3 con la intervenci\u00f3n de Mario D\u00edaz, Catedr\u00e1tico de Ingenier\u00eda Qu\u00edmica y Director de la C\u00e1tedra IPA, que abri\u00f3 la jornada realizando una breve presentaci\u00f3n. Posteriormente, Ismael Marcet, Secretario de la C\u00e1tedra IPA e Investigador del grupo TBR, realiz\u00f3 una exposici\u00f3n de la actividad desarrollada por dicho grupo de investigaci\u00f3n, as\u00ed como la oferta de productos y servicios que ofrece. Finalmente, Manuel Rendueles, Catedr\u00e1tico de Ingenier\u00eda Qu\u00edmica y Subdirector de la C\u00e1tedra IPA, realiz\u00f3 una presentaci\u00f3n sobre la oferta formativa de la universidad relacionada con el sector alimentario, dentro de la que se encuentran el m\u00e1ster oficial en Biotecnolog\u00eda Alimentaria (MBTA) y un m\u00e1ster propio de Gesti\u00f3n y Desarrollo de la Industria Alimentaria (MGYDIA).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Presentaciones de la jornada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2019\/11\/Presentaci%C3%B3n-Listeria_problem%C3%A1tica-y-control-en-la-industria.pdf\">Listeria: Problem\u00e1tica y control en la industria<\/a> (Margarita Bances)<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2019\/11\/ISMAEL-MARCET-Oferta-tecnol%C3%B3gica-y-de-servicios2.pdf\">Oferta de procesos, productos y servicios del grupo TBR<\/a> (Ismael Marcet)<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.unioviedo.es\/catedraIPA\/wp-content\/uploads\/2019\/11\/MANUEL-RENDUELES-Presentaci%C3%B3n-formaci%C3%B3n2019.pdf\">Aspectos formativos y actividades previstas<\/a> (Manuel Rendueles)<\/li><\/ul>\n\n\n<p><!--EndFragment--><br>\n<br>\n<\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado d\u00eda 27 de noviembre tuvo lugar una enriquecedora reuni\u00f3n en la que fluy\u00f3 la comunicaci\u00f3n entre representantes de diferentes empresas del Polo Alimentario de la Universidad de Oviedo y representantes del grupo de investigaci\u00f3n de Tecnolog\u00eda de Bioprocesos y Reactores (TBR), del Departamento de Ingenier\u00eda Qu\u00edmica y Tecnolog\u00eda del Medio Ambiente de la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":446,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":1,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"predecessor-version":[{"id":445,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/443\/revisions\/445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/media\/446"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}