{"id":593,"date":"2020-07-28T10:17:45","date_gmt":"2020-07-28T10:17:45","guid":{"rendered":"https:\/\/www.unioviedo.es\/poloalimentario\/?p=593"},"modified":"2020-07-28T10:34:37","modified_gmt":"2020-07-28T10:34:37","slug":"los-ensayos-de-desafio-herramientas-de-seguridad","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/poloalimentario\/los-ensayos-de-desafio-herramientas-de-seguridad\/","title":{"rendered":"Los ensayos de desaf\u00edo, herramientas de seguridad"},"content":{"rendered":"\n<p>Extra\u00eddo del diario La Nueva Espa\u00f1a, 19 de julio 2020. <\/p>\n\n\n\n<p style=\"text-align:center\" class=\"has-medium-font-size\"><em>\u00abLas pruebas cient\u00edficas en laboratorio informan de la evoluci\u00f3n de los pat\u00f3genos en la fabricaci\u00f3n de la comida\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:10% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2020\/07\/imagen-juan-diaz-1-150x150.jpg\" alt=\"\" class=\"wp-image-594\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:25px\">Juan D\u00edaz<\/p>\n<\/div><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-background has-very-light-gray-color has-vivid-cyan-blue-background-color\"><strong> El gerente de la Asociaci\u00f3n de Industrias C\u00e1rnicas de Asturias, Juan D\u00edaz, explica c\u00f3mo los laboratorios ayudan a la seguridad alimentaria con los ensayos de desaf\u00edo en los\u00a0 que inoculan,\u00a0 en entornos controlados, pat\u00f3genos para estudiar su evoluci\u00f3n en simulaciones de fabricaci\u00f3n\u00a0 del alimento.<\/strong><\/p>\n\n\n\n<p>\u201cLa mejor victoria es la\nque se consigue sin combatir\u201d. Esa es la esencia del escrito titulado <em>El\nArte de la Guerra<\/em>, el hist\u00f3rico manual de estrategia escrito por SunTzu. Y\npara ello, es necesario conocer a tu adversario con el mayor grado de detalle\nposible. Esa es una de las conclusiones que se pueden extraer de este hist\u00f3rico\nmanual de la estrategia. Conoce a tu ej\u00e9rcito conoce a tu adversario, y trata\nde vencer sin combatir.<\/p>\n\n\n\n<p>En el \u00e1mbito de la seguridad alimentaria y la salud, el laboratorio es el campo de batalla, y la estrategia se desarrolla a trav\u00e9s de la Ciencia. \u00c9sta sin duda, es la herramienta maestra que nos va a ayudar a desentra\u00f1ar el complejo comportamiento de algunos agentes y microorganismos que en una determinada situaci\u00f3n y momento pueden comprometer la seguridad del consumidor. El gran trabajo desarrollado durante los \u00faltimos a\u00f1os por la industria alimentaria, para evaluar y conocer los posibles riesgos que pueden comprometer dicha seguridad, ha derivado en que actualmente por suerte, en nuestra industria alimentaria, apenas se produzcan de manera puntual y anecd\u00f3tica, situaciones comprometidas que, desde luego, no son deseables. Y es que nuestras industrias cuentan con exigentes herramientas, exhaustivos protocolos y procesos controlados que garantizan en todo momento la seguridad y calidad de los alimentos.<\/p>\n\n\n\n<p> Una de las herramientas que la Ciencia nos proporciona para evaluar c\u00f3mo es el comportamiento de determinados pat\u00f3genos capaces de provocar toxiinfecciones alimentarias (los m\u00e1s conocidos son <em>Salmonella <\/em>spp<em>.<\/em> y <em>Listeria monocytogenes<\/em>) son los ensayos de desaf\u00edo (<em>\u201cchallenge test\u201d<\/em>). Estos estudios, permiten evaluar si estos pat\u00f3genos pueden crecer en una matriz alimentaria dada, bajo unas condiciones de producci\u00f3n determinadas, e incluso es posible determinar su velocidad de crecimiento. Tener esta informaci\u00f3n permite al productor  de alimentos decidir sobre\nla vida \u00fatil de un producto o el procesado tecnol\u00f3gico m\u00e1s adecuado. De hecho,\nel Reglamento (CE) n\u00ba 2073\/2005, relativo a los criterios microbiol\u00f3gicos\naplicables a los productos alimenticios, es especialmente exigente sobre la\nnecesidad de que el fabricante de un alimento listo para el consumo, verifique\nen relaci\u00f3n con <em>Listeria monocytogenes<\/em>,\nla vida \u00fatil del mismo. <\/p>\n\n\n\n<p>Sin embargo, para desarrollar estos estudios, la mayor dificultad aparece como consecuencia de que, como ya he mencionado anteriormente, la presencia de estos pat\u00f3genos en alimentos, es pr\u00e1cticamente marginal, como consecuencia de los estrictos protocolos de higiene, limpieza y desinfecci\u00f3n que implementa a diario la industria alimentaria. Por lo que, el desarrollo de los ensayos de desaf\u00edo, para conocer el comportamiento de nuestro adversario, requiere inocular el microorganismo a estudiar sobre el alimento, y ver c\u00f3mo \u00e9ste se comporta a lo largo de todo su proceso de fabricaci\u00f3n. Esta actividad, por lo tanto, solamente se puede desarrollar en entornos controlados como, por ejemplo, espacios de demostraci\u00f3n o plantas piloto, en los que sea posible simular los procesos de fabricaci\u00f3n del alimento que se desea ensayar, y, mantener las m\u00e1s estrictas condiciones de seguridad higiene y desinfecci\u00f3n. Adem\u00e1s, los ensayos de laboratorio utilizados para estudiar estos microorganismos, han de realizarse con el m\u00e1ximo grado de garant\u00eda, t\u00e9cnico y de calidad y regirse por los m\u00e1s estrictos protocolos de ejecuci\u00f3n (los que otorga trabajar bajo la acreditaci\u00f3n de ENAC en la norma ISO:17025). Esto garantiza la obtenci\u00f3n de resultados certeros y precisos, que tengan validez legal y puedan ser reconocidos por las autoridades competentes en materia de seguridad alimentaria.<\/p>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-medium-font-size has-vivid-cyan-blue-color\"><em><strong>\u00abAsturias tiene la \u00fanica planta piloto y el \u00fanico laboratorio de Espa\u00f1a acreditados por la ENAC para hacer &#8216;challenge test'\u00bb<\/strong><\/em><\/p>\n\n\n\n<p>No cabe duda que el reto es evidente Mediante el \u201c<em>challenge test\u201d<\/em>, se estudiar\u00e1 c\u00f3mo crece un determinado microorganismo, a qu\u00e9 velocidad y bajo qu\u00e9 condiciones (temperaturas, tiempos, pH, disponibilidad de agua, concentraci\u00f3n de conservantes). Conocer toda esta informaci\u00f3n nos ayudar\u00e1 a modificar par\u00e1metros de elaboraci\u00f3n y fabricaci\u00f3n que nos permitir\u00e1n conseguir, como es deseable, que el microorganismo se elimine o no crezca al final del proceso productivo.<\/p>\n\n\n\n<p>Imaginemos por ejemplo el\nensayo de un \u201c<em>challenge test\u201d<\/em> en un producto c\u00e1rnico, un embutido en el\nque queremos plantear una formulaci\u00f3n con el uso \u00fanicamente de conservantes\nnaturales, como el ajo y otras especias. Plantearemos el estudio fabricando un\nvolumen reducido de producto (en una planta piloto) en el que ensayaremos diferentes\nconcentraciones de esos conservantes, puesto que el objetivo es adaptar la nueva\nformulaci\u00f3n sin que la seguridad alimentaria se vea comprometida. Prepararemos varias\nmasas c\u00e1rnicas con las diferentes concentraciones de conservantes, e inocularemos\nel pat\u00f3geno en las mismas, despu\u00e9s de los procesos de picado adobado y amasado.\nA continuaci\u00f3n, desarrollaremos los procesos de embutido ahumado y secado, para\nfinalmente envasar el producto, y conservarlo en las condiciones de temperatura\ny humedad adecuadas. &nbsp;<\/p>\n\n\n\n<p>Pues bien, paso a paso y\nen cada una de esas etapas, iremos controlando c\u00f3mo se comporta el microorganismo\ninoculado, en relaci\u00f3n con la concentraci\u00f3n de conservantes naturales a\u00f1adido e\niremos comprobando qu\u00e9 formulaci\u00f3n nos proporciona un mayor grado de inhibici\u00f3n\nsobre el crecimiento del microorganismo. <\/p>\n\n\n\n<p>La informaci\u00f3n recopilada\nal inicio, durante y al final del proceso, es de un valor incalculable, y puede\nayudar a tomar decisiones para modificar los procesos de fabricaci\u00f3n, o incluso\nlos ingredientes y formulaciones de los alimentos para evitar la presencia de\ntan indeseables compa\u00f1eros de viaje, y conseguir esa \u201cvictoria sin combate\u201d.<\/p>\n\n\n\n<p>La\nindustria c\u00e1rnica asturiana y la agroalimentaria, est\u00e1n en una situaci\u00f3n\nprivilegiada para conseguir el objetivo de garantizar la seguridad alimentaria\na trav\u00e9s de los \u201c<em>challenge test\u201d.<\/em> Cuentan con la \u00fanica planta piloto y el\n\u00fanico laboratorio de todo el territorio nacional acreditado por ENAC para hacer\nestos ensayos de desaf\u00edo. Porque estar preparado para combatir, es la mejor f\u00f3rmula\npara vencer. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extra\u00eddo del diario La Nueva Espa\u00f1a, 19 de julio 2020. \u00abLas pruebas cient\u00edficas en laboratorio informan de la evoluci\u00f3n de los pat\u00f3genos en la fabricaci\u00f3n de la comida\u00bb Juan D\u00edaz El gerente de la Asociaci\u00f3n de Industrias C\u00e1rnicas de Asturias, Juan D\u00edaz, explica c\u00f3mo los laboratorios ayudan a la seguridad alimentaria con los ensayos de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-593","post","type-post","status-publish","format-standard","hentry","category-noticias","category-red-sostalimen"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":2,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"predecessor-version":[{"id":598,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/593\/revisions\/598"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/tags?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}