{"id":616,"date":"2020-08-31T20:14:43","date_gmt":"2020-08-31T20:14:43","guid":{"rendered":"https:\/\/www.unioviedo.es\/poloalimentario\/?p=616"},"modified":"2020-09-01T07:45:18","modified_gmt":"2020-09-01T07:45:18","slug":"la-leche-puede-contar-la-vida-de-la-vaca","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/poloalimentario\/la-leche-puede-contar-la-vida-de-la-vaca\/","title":{"rendered":"La leche puede contar la vida de la vaca"},"content":{"rendered":"\n<p>Extra\u00eddo del diario La Nueva Espa\u00f1a, 2 de agosto de 2020.<\/p>\n\n\n\n<p style=\"text-align:center\" class=\"has-medium-font-size\"><em>\u00abHay mol\u00e9culas en el alimento que, como biomarcadores, sirven para trazar el origen y la alimentaci\u00f3n de los animales productores\u00bb<\/em><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:10% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2020\/09\/Luis-Royo.jpg\" alt=\"\" class=\"wp-image-618\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:25px\">Luis Royo <\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide\" style=\"grid-template-columns:10% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2020\/09\/Loubna-Abou.jpg\" alt=\"\" class=\"wp-image-620\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<p style=\"font-size:25px\">\n\nLoubna Abou el Qassim\n\n<\/p>\n<\/div><\/div>\n\n\n\n<p style=\"text-align:center\" class=\"has-text-color has-background has-very-light-gray-color has-vivid-cyan-blue-background-color\"><strong>El Servicio Regional de Investigaci\u00f3n y desarrollo Agroalimentario (Serida) busca mol\u00e9culas propias de la leche que permitan asociar su presencia a un sistema de producci\u00f3n, as\u00ed podr\u00e1n servir como biomarcadores espec\u00edficos de la leche de vaca seg\u00fan su origen, lo que ahorrar\u00eda tiempo y gastos.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.unioviedo.es\/poloalimentario\/wp-content\/uploads\/2020\/07\/Logo-de-la-Red-Nuevo-2.png\" alt=\"\" class=\"wp-image-582\" width=\"361\" height=\"91\"\/><\/figure><\/div>\n\n\n\n<p>Hace unos doscientos millones de a\u00f1os\naparecieron los mam\u00edferos en la tierra como una nueva clase de animales con dos\ncaracter\u00edsticas evolutivas nuevas, la presencia de pelo y de gl\u00e1ndulas mamarias,\ncuya secreci\u00f3n (la leche) cumple el papel de alimentar a las cr\u00edas. El Hombre ha\ndesviado la funci\u00f3n de la lactancia de las hembras de algunos mam\u00edferos para su\npropio beneficio, convirtiendo la leche en un alimento presente en su alimentaci\u00f3n.\nEn concreto, los animales m\u00e1s usados para producir leche actualmente son los\nbovinos. Mediante los programas de selecci\u00f3n gen\u00e9tica y el manejo de la alimentaci\u00f3n,\nse ha creado un modelo de vaca con una lactaci\u00f3n que dura hasta 10 meses y con unas\nproducciones que alcanzan hasta 40 litros diarios en su pico de lactaci\u00f3n.<\/p>\n\n\n\n<p>Desde los a\u00f1os 90, este sector ha\nvivido una intensificaci\u00f3n que implica maximizar los litros producidos en\nestabulaci\u00f3n permanente con una dieta basada en ensilado de ma\u00edz, ensilado de\nhierba, henos y concentrados. No obstante, la alta producci\u00f3n en cantidad se\nacompa\u00f1a de bajas tasas de grasa y prote\u00edna en la leche, adem\u00e1s de los\nproblemas de fertilidad y de salud, especialmente mastitis y problemas en los\naplomos, que conducen a una reducci\u00f3n de la vida \u00fatil de los animales. Adem\u00e1s,\neste tipo de producci\u00f3n tiene una importante repercusi\u00f3n en el plano medio\nambiental, con un considerable consumo de recursos naturales y la aparici\u00f3n de\nproblemas derivados de la gesti\u00f3n de los purines. Todo lo anterior, conllev\u00f3\nplantear un modelo de producci\u00f3n integrado que toma en cuenta, adem\u00e1s de la\nproductividad, el medio ambiente, el bienestar animal y la salud humana,\nreconduciendo los sistemas de alimentaci\u00f3n hacia una utilizaci\u00f3n racional de\npraderas y prados, lo que adem\u00e1s permite una menor dependencia del exterior. En\nestas ganader\u00edas (extensivas) la productividad por hect\u00e1rea es baja y los\nbeneficios econ\u00f3micos se obtienen a largo plazo, pero cumplen una serie de\nrequisitos ambientales y \u00e9ticos que les concede una imagen positiva ante el\nconsumidor.<\/p>\n\n\n\n<p>Una vez vistas las diferencias entre\nlas ganader\u00edas intensivas y extensivas cabe preguntarse: \u00bfComo puede saber el\nconsumidor qu\u00e9 tipo de leche est\u00e1 comprando? Normalmente esta informaci\u00f3n se\nencuentra en las etiquetas descriptoras del producto, lo que requiere un\ntrabajo previo de trazabilidad del producto y de seguimiento en toda la cadena\nde producci\u00f3n, lo que requiere mucho tiempo y gastos. La alternativa que\nestamos estudiando en el Servicio Regional de Investigaci\u00f3n y Desarrollo Agroalimentario\n(SERIDA) es la b\u00fasqueda de mol\u00e9culas propias de la leche que permitan asociar\nsu presencia a un sistema de producci\u00f3n, y que podr\u00e1n servir como biomarcadores\nespec\u00edficos de la leche de vaca seg\u00fan su origen. <\/p>\n\n\n\n<p style=\"text-align:center\"><strong>Entonces, \u00bfPuede contar la leche su propia historia? <\/strong><\/p>\n\n\n\n<p>La leche es un l\u00edquido complejo, con muchos\ncomponentes nutricionales como az\u00facares (lactosa), prote\u00ednas (case\u00ednas) y\n\u00e1cidos grasos. Que el tipo de alimentaci\u00f3n se refleja de manera clara en la\ncomposici\u00f3n de la leche es algo demostrado: la leche producida por animales en pastoreo\ntiene un mayor porcentaje de \u00e1cidos grasos insaturados y antioxidantes, lo que\nredunda en un efecto positivo sobre la salud del consumidor.<\/p>\n\n\n\n<p>Pero adem\u00e1s la leche contiene bacterias\ny mol\u00e9culas bioactivas. Unas de estas mol\u00e9culas bioactivas son los microARNs, que\nson ARN cortos de 21 a 25 nucle\u00f3tidos, que est\u00e1n presentes en todos los fluidos\ndel organismo de animales y plantas, y cuya funci\u00f3n es la regulaci\u00f3n de los genes.\nLos perfiles de los microARNs cambian seg\u00fan su contexto gen\u00e9tico (especie y\nraza), pero tambi\u00e9n seg\u00fan las condiciones ambientales, lo que hace de ellos\nposibles marcadores del sistema de producci\u00f3n, como por ejemplo ciertos miRNA\nque hemos encontrado en leche cruda asociados al consumo de forraje verde y a\nla producci\u00f3n en ecol\u00f3gico.<\/p>\n\n\n\n<p>La leche, que apareci\u00f3 como una ventaja\nevolutiva de los mam\u00edferos, se ha convertido en un producto agroalimentario diferenciado,\npresente en el mercado en tipos y formas diferentes para adaptarse a diferentes\ngustos, lo que implica la necesidad de tener un sistema de trazabilidad para\ndar informaci\u00f3n precisa y suficiente al consumidor. Sobre la base de los\nestudios conducidos en el SERIDA y en otros laboratorios, se puede decir que a\ntrav\u00e9s de la leche se puede saber mucho sobre el manejo de los animales y el\nprocesamiento tecnol\u00f3gico sufrido hasta el producto final. El estudio de los\nmicroARNs abre adem\u00e1s una puerta para la investigaci\u00f3n del car\u00e1cter funcional\nde la leche y su efecto sobre la salud del consumidor, ya que sabemos que\nmicroARNs presentes en la leche cuando es administrada v\u00eda oral, atraviesan la\nbarrera intestinal y llegan a los tejidos del consumidor, donde pueden ejercer\nsu funci\u00f3n.<\/p>\n\n\n\n<p>Este trabajo est\u00e1 parcialmente\nfinanciado por el Principado de Asturias GRUPIN NySA (IDI\/2018\/000237),\ncofinanciado con fondos FEDER. Loubna Abou el Qassim est\u00e1 financiada por un\nContrato Predoctoral Severo Ochoa (BP17-49). <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Extra\u00eddo del diario La Nueva Espa\u00f1a, 2 de agosto de 2020. \u00abHay mol\u00e9culas en el alimento que, como biomarcadores, sirven para trazar el origen y la alimentaci\u00f3n de los animales productores\u00bb Luis Royo Loubna Abou el Qassim El Servicio Regional de Investigaci\u00f3n y desarrollo Agroalimentario (Serida) busca mol\u00e9culas propias de la leche que permitan asociar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-616","post","type-post","status-publish","format-standard","hentry","category-noticias","category-red-sostalimen"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/comments?post=616"}],"version-history":[{"count":5,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/616\/revisions"}],"predecessor-version":[{"id":631,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/616\/revisions\/631"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/media?parent=616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/categories?post=616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/tags?post=616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}