{"id":65,"date":"2018-02-19T17:18:29","date_gmt":"2018-02-19T17:18:29","guid":{"rendered":"https:\/\/www.unioviedo.es\/poloalimentario\/pawp\/?p=65"},"modified":"2018-02-20T18:35:11","modified_gmt":"2018-02-20T18:35:11","slug":"no-hay-pruebas-cientificas-de-que-las-dietas-sin-gluten-sean-mejores-para-la-salud","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/poloalimentario\/no-hay-pruebas-cientificas-de-que-las-dietas-sin-gluten-sean-mejores-para-la-salud\/","title":{"rendered":"No hay pruebas cient\u00edficas de que las dietas sin gluten sean mejores para la salud"},"content":{"rendered":"<p>Las dietas sin gluten son cada vez m\u00e1s populares entre la poblaci\u00f3n general. Este tipo de alimentaci\u00f3n restrictiva se ha popularizado como una opci\u00f3n saludable para perder peso u optimizar el rendimiento f\u00edsico.<\/p>\n<p>En el marco del proyecto\u00a0<a href=\"http:\/\/www.agenciasinc.es\/Noticias\/La-nueva-web-Nutrimedia-ofrece-analisis-cientificos-sobre-alimentacion\" target=\"_blank\" rel=\"noopener\">Nutrimedia<\/a>, los expertos del Observatorio de Comunicaci\u00f3n Cient\u00ed<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-57 alignright\" src=\"https:\/\/www.unioviedo.es\/poloalimentario\/pawp\/wp-content\/uploads\/2018\/02\/PoloAlimentario_servicios__foto_03-201x300.jpg\" alt=\"\" width=\"378\" height=\"564\" \/><\/p>\n<p>fica de la Universitat Pompeu Fabra ha<\/p>\n<p>n\u00a0puesto en duda que los adultos sanos seguidores de una dieta libre de este conjunto de prote\u00ednas obtengan alg\u00fan tipo de beneficio para la salud.<\/p>\n<p>Para ell<\/p>\n<p>&nbsp;<\/p>\n<p>o, han realizado un\u00a0<a href=\"https:\/\/www.upf.edu\/documents\/35405748\/36238404\/07-gluten-7g.pdf\/85a03e28-78ad-fe14-a122-ff6a8a3ada5a\" target=\"_blank\" rel=\"noopener\">an\u00e1lisis<\/a>\u00a0sobre los dos estudios cient\u00edficos al respecto, ambos observacionales,\u00a0llevados a cabo en EEUU y basados en encuestas sobre salud y nutrici\u00f3n.<\/p>\n<div class=\"lado frt\">\n<p>El gluten podr\u00eda reducir el riesgo de infarto y es importante para la absorci\u00f3n de nutrientes<\/p>\n<\/div>\n<p>Los especialistas apuntan que estas investigaciones presentan una calidad global muy baja y que en ning\u00fan caso pueden establecer una relaci\u00f3n directa entre el consumo de alimentos sin gluten y un correspondiente beneficio para la salud en adultos.<\/p>\n<p>Al contrario, sugieren que su ingesta en personas sin ning\u00fan tipo de intolerancia o alergia al compuesto podr\u00eda ser m\u00ednimamente m\u00e1s beneficiosa que una alimentaci\u00f3n que carezca de \u00e9l.<\/p>\n<p><strong>Beneficios del consumo de gluten<\/strong><\/p>\n<p>Trabajos anteriores han comprobado que eliminar el gluten de la dieta sin prescripci\u00f3n m\u00e9dica implica una disminuci\u00f3n del consumo de granos enteros y fibra que, adem\u00e1s de saciar el apetito, son beneficiosos para la salud cardiovascular. Con esto, las<\/p>\n<p>&nbsp;<\/p>\n<p>pruebas cient\u00edficas evidencian que el gluten podr\u00eda reducir levemente el riesgo de infarto.<\/p>\n<p>Con respecto a la aportaci\u00f3n cal\u00f3rica, los estudios muestran, en contra de las creencias populares, que el seguimiento de una dieta libre de gluten en personas celiacas puede conllevar\u00a0un incremento de peso. Esto ocurre porque al consumir este compuesto, se\u00a0producir\u00eda una inflamaci\u00f3n en\u00a0el intestino, dificultando la absorci\u00f3n de nutrientes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>En el momento en el que se comienza una dieta que prescinde de este conjunto de prote\u00ednas, la inflamaci\u00f3n mejora y con ello la absorci\u00f3n. Los expertos desmitifican as\u00ed el uso de esta alimentaci\u00f3n como m\u00e9todo de p\u00e9rdida de peso.<\/p>\n<div class=\"lado flt\">\n<p>Los alimentos sin gluten no tienen mejores valores nutricionales que sus hom\u00f3logos con este compuesto<\/p>\n<\/div>\n<p>Asimismo, el consumo de gluten es importante para la absorci\u00f3n de nutrientes\u00a0como el calcio o la vitamina D.\u00a0Los autores de ambos estudios concluyeron que es poco probable que los alimentos sin gluten aporten beneficios en salud, a menos que haya una clara recomendaci\u00f3n para su consumo.<\/p>\n<p>Entonces,\u00a0<a href=\"http:\/\/www.agenciasinc.es\/Noticias\/La-celiaquia-se-estanca-pero-la-dieta-sin-gluten-sigue-ganando-adeptos\" target=\"_blank\" rel=\"noopener\">\u00bfpor qu\u00e9 cada vez m\u00e1s personas deciden seguir una dieta de este tipo?<\/a>\u00a0Seg\u00fan los especialistas, el aumento en las ventas de productos\u00a0<em>gluten free<\/em>\u00a0parece obedecer a potentes campa\u00f1as de\u00a0<em>marketing<\/em>\u00a0m\u00e1s que a una mejora de la salud del consumidor.<\/p>\n<p><strong>Acudir al especialista<\/strong><\/p>\n<p>De ah\u00ed que la Federaci\u00f3n de Asociaciones de Celiacos de Espa\u00f1a (FACE) no recomiende el inicio de una dieta sin gluten sin antes haber sido evaluado por un especialista, dado que esto dificultar\u00eda el diagn\u00f3stico de cualquier patolog\u00eda asociada a su consumo o la intolerancia a otro tipo de sustancias.<\/p>\n<p>Muchas personas se consideran sensibles al gluten en ausencia de enfermedad celiaca y siguen dietas exentas de este compuesto. Sin embargo, los s\u00edntomas pueden originarse por la ingesta de otro tipo de sustancias como lactosa, fructosa o galactanos (legumbres), entre otros. De ah\u00ed la importancia de realizar un correcto diagn\u00f3stico de la sensibilidad al gluten no celiaca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las dietas sin gluten son cada vez m\u00e1s populares entre la poblaci\u00f3n general. Este tipo de alimentaci\u00f3n restrictiva se ha popularizado como una opci\u00f3n saludable para perder peso u optimizar el rendimiento f\u00edsico. En el marco del proyecto\u00a0Nutrimedia, los expertos del Observatorio de Comunicaci\u00f3n Cient\u00ed fica de la Universitat Pompeu Fabra ha n\u00a0puesto en duda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-65","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/comments?post=65"}],"version-history":[{"count":1,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/65\/revisions"}],"predecessor-version":[{"id":66,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/posts\/65\/revisions\/66"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/media\/16"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/media?parent=65"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/categories?post=65"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/poloalimentario\/wp-json\/wp\/v2\/tags?post=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}