{"id":2605,"date":"2023-11-02T10:19:38","date_gmt":"2023-11-02T10:19:38","guid":{"rendered":"https:\/\/www.unioviedo.es\/talentuo\/?p=2605"},"modified":"2024-12-17T16:34:21","modified_gmt":"2024-12-17T15:34:21","slug":"plan-de-empleo-primera-experiencia-profesional-2023-24-promovido-por-el-ayuntamiento-de-gijon-xixon","status":"publish","type":"post","link":"https:\/\/www.unioviedo.es\/talentuo\/plan-de-empleo-primera-experiencia-profesional-2023-24-promovido-por-el-ayuntamiento-de-gijon-xixon\/","title":{"rendered":"Plan de Empleo Primera Experiencia Profesional 2023-24, promovido por el Ayuntamiento de Gij\u00f3n\/Xix\u00f3n"},"content":{"rendered":"<div>\n<p>El Ayuntamiento de Gij\u00f3n acaba ha publicado las bases del Plan de Empleo Primera Experiencia Profesional 2023-24, dentro de la Convocatoria 2023 del Servicio P\u00fablico de Empleo del Principado de Asturias de subvenciones para la realizaci\u00f3n de <strong>contratos formativos para la obtenci\u00f3n de la pr\u00e1ctica profesional adecuada al nivel de estudios, de un a\u00f1o de duraci\u00f3n<\/strong>.<\/p>\n<p>Requisitos:<\/p>\n<ul>\n<li>Estar en situaci\u00f3n de desempleo<\/li>\n<li>Ser menor de 30 a\u00f1os,<\/li>\n<li>A la fecha de formalizaci\u00f3n del contrato, estar inscrito\/a como demandante de empleo no ocupadas, en el Servicio p\u00fablico de empleo de Asturias, y en el Sistema de Garant\u00eda juvenil.<\/li>\n<\/ul>\n<\/div>\n<div>\n<p>Plazo de solicitud: <strong>hasta el 3 de noviembre<\/strong> incluido<\/p>\n<p>M\u00e1s informaci\u00f3n: <strong><span style=\"color: #008000;\"><a style=\"color: #008000;\" href=\"https:\/\/sedeelectronica.gijon.es\/sta\/CarpetaPublic\/doEvent?APP_CODE=STA&amp;PAGE_CODE=SEDE_PROMOCION_POLITICAS_DETALLE&amp;DBOID=6263930805753141306402&amp;REQID=2&amp;HFC=GJ_HEADER#GJ_FOOTER&amp;SESSION_REQUIRED=false\">Sede electr\u00f3nica del Ayuntamiento de Gij\u00f3n\u00a0<\/a><\/span><\/strong><\/p>\n<hr \/>\n<blockquote><p>Si est\u00e1s buscando empleo, no olvide registrarte &#8211; si a\u00fan no lo has hecho- en la <a href=\"https:\/\/www.unioviedo.es\/talentuo\/agencia-de-colocacion\/\">Agencia de colocaci\u00f3n<\/a> de la Universidad de Oviedo.<\/p>\n<p>Puedes seguir noticias y novedades en <a href=\"https:\/\/empleotalentuo.com\/\">Herramientas para el Empleo TalentUO<\/a> y otras actualizaciones de Empleo y Emprendimiento tambi\u00e9n en <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2814 \" src=\"https:\/\/www.unioviedo.es\/talentuo\/wp-content\/uploads\/2023\/12\/logo-mini-linkedin-1.png\" alt=\"\" width=\"29\" height=\"30\" \/><a href=\"https:\/\/www.linkedin.com\/company\/talentuoviedo\/\">TalentUO\u00a0<\/a><\/p><\/blockquote>\n<blockquote><p><a href=\"https:\/\/www.unioviedo.es\/talentuo\/noticias\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3874 alignright\" src=\"https:\/\/www.unioviedo.es\/talentuo\/wp-content\/uploads\/2024\/12\/mas-noticias-300x80.jpg\" alt=\"Bot\u00f3n con las palabras &quot;m\u00e1s noticias&quot; que enlaza al apartado de Noticias de esta web\" width=\"244\" height=\"65\" srcset=\"https:\/\/www.unioviedo.es\/talentuo\/wp-content\/uploads\/2024\/12\/mas-noticias-300x80.jpg 300w, https:\/\/www.unioviedo.es\/talentuo\/wp-content\/uploads\/2024\/12\/mas-noticias.jpg 482w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/><\/a><\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Gij\u00f3n acaba ha publicado las bases del Plan de Empleo Primera Experiencia Profesional 2023-24, dentro de la Convocatoria 2023 del Servicio P\u00fablico de Empleo del Principado de Asturias de subvenciones para la realizaci\u00f3n de contratos formativos para la obtenci\u00f3n de la pr\u00e1ctica profesional adecuada al nivel de estudios, de un a\u00f1o de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[55],"class_list":["post-2605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-plan-de-empleo"],"_links":{"self":[{"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/posts\/2605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/comments?post=2605"}],"version-history":[{"count":7,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/posts\/2605\/revisions"}],"predecessor-version":[{"id":3930,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/posts\/2605\/revisions\/3930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/media\/2604"}],"wp:attachment":[{"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/media?parent=2605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/categories?post=2605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unioviedo.es\/talentuo\/wp-json\/wp\/v2\/tags?post=2605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}